{"id":369,"date":"2012-04-04T13:54:41","date_gmt":"2012-04-04T13:54:41","guid":{"rendered":"http:\/\/www.art-events.de\/weblog\/?p=369"},"modified":"2021-07-23T16:26:36","modified_gmt":"2021-07-23T16:26:36","slug":"homedir-beliebige-dokumente-fotos-und-mehr-in-der-artikelverwaltung","status":"publish","type":"post","link":"https:\/\/www.art-events.de\/weblog\/homedir-beliebige-dokumente-fotos-und-mehr-in-der-artikelverwaltung\/","title":{"rendered":"HomeDir &#8211; beliebige Dokumente, Fotos und mehr in der Artikelverwaltung"},"content":{"rendered":"<p>Was &#8211; so finden wir &#8211; jedes Programm f\u00fcr Lagerverwaltung und Artikelverwaltung haben m\u00fcsste: ein Artikelheimatverzeichnis! Dort wo der Artikel zu Hause ist = dort wo, sich weitere Dokumente und Fotos, St\u00fccklisten, Baupl\u00e4ne, Zertifikate und was sonst noch alles zum Artikel geh\u00f6rt speichern l\u00e4sst!<\/p>\n<p>Und wie das alles mit einer Software verarbeiten? Einfach auf Mouseclick den Datei Explorer \u00f6ffnen &#8211; fertig. Dann geht es mit der Mouse weiter: beim Clicken werden jeweils die zugeordenten Anwendungen gestartet. F\u00fcr Fotos der Bildbetrachter, f\u00fcr Officedokumente das entsprechende Programm usw usf.<\/p>\n<p>Die Lagerverwaltung wird damit zum Frontend &#8211; zur Datenmaske, um weitere INformationen \u00fcber einen gew\u00fcnschten Artikel zu erhalten. Informationen, die nicht Bestandteil einer genormten Lagererfassung sind.<\/p>\n<p>Ist das denn nun Utopie? &#8211; Nein, ganz und gar nicht. Moderne Lagerprogramme haben so etwas schon. Nat\u00fcrlich auch unsere Lager- und Artikelverwaltung AE WWS Lite Win. Dort kann f\u00fcr jeden Artikel ein Heimatverzeichnis (HomeDir) spezifiziert werden und dann lass sich die o.a. Sachen realisieren.<\/p>\n<p>Wer es ausprobieren m\u00f6chte: kein Problem &#8211; bereits die kostenlos &amp; umsonst Demoversino unerst\u00fctzt das HomeDir Prinzip. Weitere Informationen direkt hier:<\/p>\n<p><a href=\"https:\/\/www.terminal-systems.de\/wp\/home-2\/lager1\/lagerverwaltung-aktuell\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.terminal-systems.de\/wp\/home-2\/lager1\/lagerverwaltung-aktuell\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was &#8211; so finden wir &#8211; jedes Programm f\u00fcr Lagerverwaltung und Artikelverwaltung haben m\u00fcsste: ein Artikelheimatverzeichnis! Dort wo der Artikel zu Hause ist = dort wo, sich weitere Dokumente und Fotos, St\u00fccklisten, Baupl\u00e4ne, Zertifikate und was sonst noch alles zum Artikel geh\u00f6rt speichern l\u00e4sst! Und wie das alles mit einer Software verarbeiten? Einfach auf Mouseclick [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","hentry","category-anwendungen","entry"],"_links":{"self":[{"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":0,"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.art-events.de\/weblog\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}